{"id":10832,"date":"2020-11-24T20:05:03","date_gmt":"2020-11-24T20:05:03","guid":{"rendered":"https:\/\/enlightenment-demo.onedesigns.com\/events\/?post_type=tribe_events&#038;eventDate=2026-02-07#038;p=373"},"modified":"2020-11-24T20:05:03","modified_gmt":"2020-11-24T20:05:03","slug":"alternative-sound-party-2026-02-07","status":"publish","type":"tribe_events","link":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/","title":{"rendered":"Alternative Sound Party"},"content":{"rendered":"\n\n\n<p>Etiam pulvinar mauris feugiat est volutpat elementum. Vivamus semper auctor leo sit amet blandit. Sed dictum, dolor ut commodo eleifend, ligula velit porttitor mauris, ut luctus lorem diam eu felis. Nam lacinia risus eget eros finibus, eget varius sapien pharetra. Vivamus fringilla augue in vestibulum porta. Vestibulum sit amet velit tempus, dignissim lectus quis, porttitor tellus. Etiam sed mi id sem feugiat dignissim.<\/p>\n\n\n\n<!--more-->\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Etiam pulvinar mauris feugiat est volutpat elementum. Vivamus semper auctor leo sit amet blandit. Sed dictum, dolor ut commodo eleifend, ligula velit porttitor mauris, ut luctus lorem diam eu felis. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":374,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets__Commerce__PayPal__Main","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","_enlightenment_custom_layout":[],"_enlightenment_sidebar_locations":[],"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[23],"tribe_events_cat":[13],"class_list":["post-10832","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-music","tribe_events_cat-time-out","cat_time-out","tribe-recurring-event","tribe-recurring-event-child"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alternative Sound Party - Enlightenment Events<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alternative Sound Party - Enlightenment Events\" \/>\n<meta property=\"og:description\" content=\"Etiam pulvinar mauris feugiat est volutpat elementum. Vivamus semper auctor leo sit amet blandit. Sed dictum, dolor ut commodo eleifend, ligula velit porttitor mauris, ut luctus lorem diam eu felis. &#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Enlightenment Events\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OneDesigns\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/\",\"url\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/\",\"name\":\"Alternative Sound Party - Enlightenment Events\",\"isPartOf\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg\",\"datePublished\":\"2020-11-24T20:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage\",\"url\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg\",\"contentUrl\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/enlightenment-demo.onedesigns.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Events\",\"item\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/events\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Alternative Sound Party\",\"item\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2020-12-05\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Alternative Sound Party\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#website\",\"url\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/\",\"name\":\"Enlightenment Events\",\"description\":\"Just another Enlightenment Sites site\",\"publisher\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#organization\",\"name\":\"Enlightenment Events\",\"url\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/enlightenment-logo-dark-alt.png\",\"contentUrl\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/enlightenment-logo-dark-alt.png\",\"width\":96,\"height\":96,\"caption\":\"Enlightenment Events\"},\"image\":{\"@id\":\"https:\/\/enlightenment-demo.onedesigns.com\/events\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OneDesigns\",\"https:\/\/www.instagram.com\/onedesigns_com\/\",\"https:\/\/www.linkedin.com\/company\/onedesigns\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alternative Sound Party - Enlightenment Events","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Alternative Sound Party - Enlightenment Events","og_description":"Etiam pulvinar mauris feugiat est volutpat elementum. Vivamus semper auctor leo sit amet blandit. Sed dictum, dolor ut commodo eleifend, ligula velit porttitor mauris, ut luctus lorem diam eu felis. &#8230;","og_url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/","og_site_name":"Enlightenment Events","article_publisher":"https:\/\/www.facebook.com\/OneDesigns","og_image":[{"width":2560,"height":1707,"url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/","url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/","name":"Alternative Sound Party - Enlightenment Events","isPartOf":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage"},"image":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage"},"thumbnailUrl":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg","datePublished":"2020-11-24T20:05:03+00:00","breadcrumb":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#primaryimage","url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg","contentUrl":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/pexels-picjumbocom-196652-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2026-02-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enlightenment-demo.onedesigns.com\/"},{"@type":"ListItem","position":2,"name":"Home"},{"@type":"ListItem","position":3,"name":"Events","item":"https:\/\/enlightenment-demo.onedesigns.com\/events\/events\/"},{"@type":"ListItem","position":4,"name":"Alternative Sound Party","item":"https:\/\/enlightenment-demo.onedesigns.com\/events\/event\/alternative-sound-party\/2020-12-05\/"},{"@type":"ListItem","position":5,"name":"Alternative Sound Party"}]},{"@type":"WebSite","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#website","url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/","name":"Enlightenment Events","description":"Just another Enlightenment Sites site","publisher":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enlightenment-demo.onedesigns.com\/events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#organization","name":"Enlightenment Events","url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#\/schema\/logo\/image\/","url":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/enlightenment-logo-dark-alt.png","contentUrl":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-content\/uploads\/sites\/6\/2020\/11\/enlightenment-logo-dark-alt.png","width":96,"height":96,"caption":"Enlightenment Events"},"image":{"@id":"https:\/\/enlightenment-demo.onedesigns.com\/events\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OneDesigns","https:\/\/www.instagram.com\/onedesigns_com\/","https:\/\/www.linkedin.com\/company\/onedesigns\/"]}]}},"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/tribe_events\/10832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/tribe_events\/10832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/media\/374"}],"wp:attachment":[{"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/media?parent=10832"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/tags?post=10832"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/enlightenment-demo.onedesigns.com\/events\/wp-json\/wp\/v2\/tribe_events_cat?post=10832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}